{"id":18290,"date":"2023-11-13T11:06:08","date_gmt":"2023-11-13T14:06:08","guid":{"rendered":"https:\/\/fadeweb.uncoma.edu.ar\/?p=18290"},"modified":"2023-11-13T11:06:08","modified_gmt":"2023-11-13T14:06:08","slug":"conversatorio-ius-comahue-sobre-la-caducidad-de-instancia-en-el-proceso-penal-de-la-provincia-de-rio-negro-resena-jurisprudencial","status":"publish","type":"post","link":"https:\/\/fadeweb.uncoma.edu.ar\/index.php\/2023\/11\/13\/conversatorio-ius-comahue-sobre-la-caducidad-de-instancia-en-el-proceso-penal-de-la-provincia-de-rio-negro-resena-jurisprudencial\/","title":{"rendered":"CONVERSATORIO IUS COMAHUE SOBRE \u00abLA CADUCIDAD DE INSTANCIA EN EL PROCESO PENAL DE LA PROVINCIA DE R\u00cdO NEGRO: RESE\u00d1A JURISPRUDENCIAL\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-18291 alignleft\" src=\"https:\/\/fadeweb.uncoma.edu.ar\/wp-content\/uploads\/2023\/11\/Flyer-Conversatorio-Caducidad-Proceso-Penal-Rio-Negro-724x1024.jpeg\" alt=\"\" width=\"424\" height=\"600\" srcset=\"https:\/\/fadeweb.uncoma.edu.ar\/wp-content\/uploads\/2023\/11\/Flyer-Conversatorio-Caducidad-Proceso-Penal-Rio-Negro-724x1024.jpeg 724w, https:\/\/fadeweb.uncoma.edu.ar\/wp-content\/uploads\/2023\/11\/Flyer-Conversatorio-Caducidad-Proceso-Penal-Rio-Negro-212x300.jpeg 212w, https:\/\/fadeweb.uncoma.edu.ar\/wp-content\/uploads\/2023\/11\/Flyer-Conversatorio-Caducidad-Proceso-Penal-Rio-Negro-768x1086.jpeg 768w, https:\/\/fadeweb.uncoma.edu.ar\/wp-content\/uploads\/2023\/11\/Flyer-Conversatorio-Caducidad-Proceso-Penal-Rio-Negro-1086x1536.jpeg 1086w, https:\/\/fadeweb.uncoma.edu.ar\/wp-content\/uploads\/2023\/11\/Flyer-Conversatorio-Caducidad-Proceso-Penal-Rio-Negro.jpeg 1131w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/p>\n<div style=\"text-align: left;\">La revista jur\u00eddica \u201cIus Comahue\u201d invita al \u201cConversatorio Ius Comahue: La caducidad de instancia en el proceso penal de la provincia de R\u00edo Negro\u201d, que se realizar\u00e1 el viernes 17 de noviembre de 18 a 20 en el aula 5 de la FADECS.<\/p>\n<p>El encuentro contar\u00e1 con la participaci\u00f3n, en car\u00e1cter de disertante, del Dr. Gast\u00f3n Pierroni, quien es abogado, especialista en Derecho Administrativo, Derecho Penal y Ciencias Penales y en Justicia Constitucional y Derechos Humanos. Es Diplomado en Derecho Penal y Proceso Penal y maestrando en Derecho Penal y Proceso Penal. Asimismo, es Juez de Garant\u00edas del Foro de Jueces de la Segunda Circunscripci\u00f3n Judicial de R\u00edo Negro y Docente Adscripto de la C\u00e1tedra \u00abDerecho Penal I y II Tradicional\u00bb de la FADECS &#8211; UNComa.<\/p>\n<p>La charla tendr\u00e1 formato PRESENCIAL en la sede de la FADECS y\u00a0 ser\u00e1 de acceso libre y gratuito, con cupo de participantes, y con entrega de certificados.<\/p>\n<p>Est\u00e1 dirigida a estudiantes de grado, graduados\/as y posgraduados\/as de la carrera de abogac\u00eda, investigadoras\/es, integrantes del poder judicial provincial y organismos p\u00fablicos en general, profesionales en ejercicio liberal de la profesi\u00f3n y p\u00fablico en general.<\/p>\n<p>INSCRIPCI\u00d3N: <a href=\"https:\/\/forms.gle\/PyfSU9pB8gRvfEnN9\" target=\"_blank\" rel=\"noopener\">https:\/\/forms.gle\/PyfSU9pB8gRvfEnN9<\/a><\/div>\n<div style=\"text-align: left;\">\n<p>Mas informaci\u00f3n Ius Comahue o <a href=\"http:\/\/www.iuscomahue.com\/\" target=\"_blank\" rel=\"noopener\">www.iuscomahue.com<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La revista jur\u00eddica \u201cIus Comahue\u201d invita al \u201cConversatorio Ius Comahue: La caducidad de instancia en el proceso penal de la provincia de R\u00edo Negro\u201d, que se realizar\u00e1 el viernes 17 de noviembre de 18 a 20 en el aula 5 de la FADECS. El encuentro contar\u00e1 con la participaci\u00f3n, en car\u00e1cter de disertante, del Dr. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18291,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-18290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notifadecs"],"_links":{"self":[{"href":"https:\/\/fadeweb.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/18290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fadeweb.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fadeweb.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fadeweb.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fadeweb.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=18290"}],"version-history":[{"count":1,"href":"https:\/\/fadeweb.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/18290\/revisions"}],"predecessor-version":[{"id":18292,"href":"https:\/\/fadeweb.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/18290\/revisions\/18292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fadeweb.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/18291"}],"wp:attachment":[{"href":"https:\/\/fadeweb.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=18290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fadeweb.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=18290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fadeweb.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=18290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}